{"id":31013,"date":"2019-08-16T10:29:25","date_gmt":"2019-08-16T08:29:25","guid":{"rendered":"https:\/\/quilosa.com\/uso-de-cookies\/"},"modified":"2019-12-17T11:30:50","modified_gmt":"2019-12-17T10:30:50","slug":"uso-de-cookies","status":"publish","type":"page","link":"https:\/\/quilosa.com\/fr\/uso-de-cookies\/","title":{"rendered":"Politique de cookies"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1568387281259{margin-bottom: 50px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text el_class=&#8221;text_style&#8221;]<\/p>\n<h3>POLITIQUE DE COOKIES<\/h3>\n<p>Nous recueillons et utilisons les informations sur ce site web comme indiqu\u00e9 dans notre politique de confidentialit\u00e9. L&#8217;un des moyens par lesquels nous collectons des informations est via l\u2019utilisation d\u2019une technologie appel\u00e9e &#8220;cookies&#8221;. Dans Selena Iberia, nous utilisons des cookies pour plusieurs objectifs.<\/p>\n<p><strong>Qu&#8217;est-ce qu&#8217;un cookie ?<\/strong><\/p>\n<p>Un cookie est un fichier inoffensif qui est stock\u00e9 d votre ordinateur lors de l&#8217;acc\u00e8s \u00e0 certaines sites web. Les cookies permettent \u00e0 un site web notamment de stocker et de r\u00e9cup\u00e9rer des informations sur les habitudes de navigation des utilisateurs ou de leur \u00e9quipement et, en fonction des informations qu\u2019ils contiennent et de la mani\u00e8re dont ils utilisent leur \u00e9quipement.<br \/>\nAinsi, il existe des cookies qui obtiennent des informations relatives au nombre de pages visit\u00e9es, \u00e0 la ville \u00e0 laquelle l&#8217;adresse IP depuis laquelle on acc\u00e8de est assign\u00e9e, au nombre de nouveaux utilisateurs, \u00e0 la fr\u00e9quence et \u00e0 la r\u00e9currence des visites, \u00e0 l&#8217;heure de la visite, le navigateur, l&#8217;op\u00e9rateur ou le type de terminal \u00e0 partir duquel la visite est effectu\u00e9e.<\/p>\n<p><strong>Qu&#8217;est-ce que n\u2019est PAS un cookie ?<\/strong><\/p>\n<p>Ce n&#8217;est pas un virus, ni un cheval de Troie, ni un ver, ni un spam, ni un logiciel espion, ni une fen\u00eatre pop-up.<\/p>\n<p><strong>Quelles informations stocke-t-il un cookie ?<\/strong><\/p>\n<p>Les cookies ne stockent g\u00e9n\u00e9ralement pas d&#8217;informations sensibles vous concernant, telles que des num\u00e9ros de carte de cr\u00e9dit ou des coordonn\u00e9es bancaires, des photographies ou des informations personnelles, etc. Les donn\u00e9es qu\u2019ils conservent sont de nature technique et statistique, des pr\u00e9f\u00e9rences personnelles, personnalisation de contenu, etc.<\/p>\n<p>Le serveur Web ne vous associe pas en tant que personne, mais votre navigateur Web. En fait, si vous naviguez r\u00e9guli\u00e8rement avec le navigateur Chrome et essayez de naviguer sur le m\u00eame site Web avec le navigateur Firefox, vous verrez que le site Web ne r\u00e9alise pas que vous \u00eates la m\u00eame personne, car il associe les informations r\u00e9ellement au navigateur et pas \u00e0 la personne.<\/p>\n<p><strong>Quel genre de cookies existe-t-il ? <\/strong><\/p>\n<p>Cookies techniques : Ils sont les plus \u00e9l\u00e9mentaires et permettent, entre autres, de savoir quand une personne ou une application automatis\u00e9e navigue, quand un utilisateur anonyme et enregistr\u00e9 navigue, effectue des t\u00e2ches de base pour le fonctionnement de tout site Web dynamique.<\/p>\n<p>Cookies d\u2019analyse : ils collectent des informations sur le type de navigation que vous faites, les sections que vous utilisez le plus, les produits consult\u00e9s, le fuseau horaire d&#8217;utilisation, la langue, etc.<\/p>\n<p>Cookies publicitaires : ils diffusent des publicit\u00e9s en fonction de votre navigation, de votre pays d&#8217;origine, de votre langue, etc.<\/p>\n<p><strong>Que sont les cookies propres et de tiers ?<\/strong><\/p>\n<p>Les cookies propres sont ceux g\u00e9n\u00e9r\u00e9s par la page que vous visitez et ceux de tiers sont ceux g\u00e9n\u00e9r\u00e9s par des services ou fournisseurs externes tels que Mailchimp, Mailrelay, Facebook, Twitter, Google adsense, etc.<\/p>\n<p><strong>Quels cookies utilise ce site ?<\/strong><\/p>\n<p>Ce site utilise ses propres cookies et ceux de tiers. Ce site utilise les cookies suivants, d\u00e9crits ci-dessous:<\/p>\n<p><strong>Propres cookies<\/strong><\/p>\n<p>Login : Les cookies de connexion vous permettent d\u2019entrer et de sortir de votre compte Selena Iberia.<\/p>\n<p>Personnalisation : les cookies nous aident \u00e0 m\u00e9moriser les personnes ou les sites Web avec lesquels vous avez interagi, afin que nous puissions vous montrer des contenus associ\u00e9s.<\/p>\n<p>Pr\u00e9f\u00e9rences : Les cookies nous permettent de m\u00e9moriser vos param\u00e8tres et pr\u00e9f\u00e9rences, tels que la langue pr\u00e9f\u00e9r\u00e9e et vos param\u00e8tres de confidentialit\u00e9.<\/p>\n<p>S\u00e9curit\u00e9 : Nous utilisons des cookies pour \u00e9viter les risques de s\u00e9curit\u00e9. Principalement pour d\u00e9tecter les tentatives de piratage de votre compte Selena Iberia.<\/p>\n<p><strong>Cookies de tiers<\/strong><\/p>\n<p>Ce site utilise des services d&#8217;analyse, notamment Google Analytics, pour aider le site \u00e0 analyser l&#8217;utilisation faite par les utilisateurs du site et \u00e0 en am\u00e9liorer la convivialit\u00e9, mais ils ne sont en aucun cas associ\u00e9s \u00e0 des donn\u00e9es permettant d&#8217;identifier l&#8217;utilisateur. Google Analytics, est un service Web analytique fourni par Google, Inc.<br \/>\nL&#8217;utilisateur peut consulter les types de cookies utilis\u00e9s par Google sur: https:\/\/www.google.es\/intl\/es\/policies\/technologies\/types<\/p>\n<p>Les cookies des r\u00e9seaux sociaux peuvent \u00eatre stock\u00e9s dans votre navigateur lorsque vous naviguez sur nos pages, par exemple lorsque vous utilisez le bouton pour partager le contenu de www.quilosa.es ou www.quilosa.com sur un r\u00e9seau social.<br \/>\nTrouvez ci-dessous des informations sur les cookies des r\u00e9seaux sociaux que ce site utilise dans ses propres politiques en mati\u00e8re de cookies :<br \/>\nCookies de Facebook, trouvez plus d&#8217;informations sur leur politique de cookies<br \/>\nCookies de Twitter, trouvez plus d&#8217;informations sur leur politique de cookies<br \/>\nCookies de Google+, trouvez plus d&#8217;informations sur leur politique de cookies<br \/>\nCookies de Linkedin, trouvez plus d&#8217;informations sur leur politique de cookies<br \/>\nCookies de YouTube, trouvez plus d&#8217;informations sur leur politique de cookies<\/p>\n<p>Nous pouvons effectuer occasionnellement des actions de remarketing via Google AdWords, qui utilise des cookies pour nous aider \u00e0 offrir des annonces en ligne sp\u00e9cifiques bas\u00e9es sur des visites pr\u00e9c\u00e9dentes de notre site Web. Google utilise ces informations pour diffuser des annonces sur diff\u00e9rents sites Web tiers via Internet. Ces cookies sont sur le point d&#8217;expirer et ne contiennent aucune information pouvant vous identifier personnellement. Veuillez consulter la Politique de confidentialit\u00e9 de Google pour plus d&#8217;informations.<\/p>\n<p>Nous pouvons \u00e9galement mener des actions de remarketing via Facebook ads, qui utilise des cookies pour nous aider \u00e0 offrir des publicit\u00e9s en ligne sp\u00e9cifiques bas\u00e9es sur des visites pr\u00e9c\u00e9dentes de notre site Web.<\/p>\n<p><strong>Les cookies peuvent-ils \u00eatre supprim\u00e9s? <\/strong><\/p>\n<p>Oui, et non seulement supprim\u00e9s, mais aussi e bloqu\u00e9s, de mani\u00e8re g\u00e9n\u00e9rale ou particuli\u00e8re pour un domaine sp\u00e9cifique.<\/p>\n<p>Pour supprimer les cookies d&#8217;un site Web, vous devez vous rendre dans les param\u00e8tres de votre navigateur. Vous pouvez y rechercher les cookies associ\u00e9s au domaine en question et proc\u00e9der \u00e0 leur \u00e9limination.<\/p>\n<p>Param\u00e8tres de cookies pour Google Chrome<br \/>\nParam\u00e8tres de cookies pour Apple Safari<br \/>\nParam\u00e8tres de cookies pour Internet Explorer<br \/>\nParam\u00e8tres de cookies pour Mozilla Firefox<\/p>\n<p>Les cookies \u00e9tant des fichiers texte normaux, ils peuvent \u00eatre explor\u00e9s avec la plupart des \u00e9diteurs de texte ou des programmes de traitement de texte. Vous pouvez cliquer sur un cookie pour l&#8217;ouvrir. Vous trouverez ci-dessous une liste de liens sur la mani\u00e8re de voir les cookies sur les diff\u00e9rents navigateurs. Si vous utilisez un autre navigateur, consultez les informations sur les cookies sur le navigateur. Si vous utilisez un t\u00e9l\u00e9phone portable, reportez-vous au manuel de l\u2019appareil pour plus d&#8217;informations.<\/p>\n<p>Firefox :<br \/>\nhttps:\/\/support.mozilla.org\/en-US\/kb\/cookies-information-websites-store-on-your-computer<\/p>\n<p>Chrome :<br \/>\nhttps:\/\/support.google.com\/chrome\/bin\/answer.py?hl=en&#038;answer=95647&#038;topic=14666&#038;ctx=topic<\/p>\n<p>Internet Explorer 8-10 :<br \/>\nhttp:\/\/windows.microsoft.com\/en-US\/internet-explorer\/delete-manage-cookies<\/p>\n<p>Safari :<br \/>\nhttp:\/\/support.apple.com\/kb\/ph5042<\/p>\n<p>Opera :<br \/>\nhttp:\/\/help.opera.com\/Windows\/12.00\/es-ES\/cookies.html<\/p>\n<p>Voici comment acc\u00e9der \u00e0 un cookie sp\u00e9cifique sur le navigateur Chrome. Remarque : ces \u00e9tapes peuvent varier en fonction de la version du navigateur :<br \/>\nAllez dans Param\u00e8tres ou Pr\u00e9f\u00e9rences via le menu Fichier ou en cliquant sur l&#8217;ic\u00f4ne de personnalisation qui appara\u00eet en haut \u00e0 droite.<br \/>\nVous verrez diff\u00e9rentes sections, cliquez les options avanc\u00e9es sur l&#8217;option Afficher.<br \/>\nAcc\u00e9dez \u00e0 Confidentialit\u00e9, Param\u00e8tres de contenu.<br \/>\nS\u00e9lectionnez Tous les cookies et les donn\u00e9es du site.<br \/>\nUne liste avec tous les cookies tri\u00e9s par domaine appara\u00eetra. Pour faciliter la recherche des cookies d&#8217;un domaine sp\u00e9cifique, entrez l&#8217;adresse partiellement ou compl\u00e8tement dans le champ Rechercher les cookies.<br \/>\nUne fois ce filtre cr\u00e9e, une ou plusieurs lignes contenant les cookies du site Web demand\u00e9 appara\u00eetront \u00e0 l&#8217;\u00e9cran. Il ne vous reste plus qu&#8217;\u00e0 les s\u00e9lectionner et \u00e0 appuyer sur le X pour proc\u00e9der \u00e0 son \u00e9limination.<br \/>\nPour acc\u00e9der aux param\u00e8tres de cookies du navigateur Internet Explorer, proc\u00e9dez comme suit (il peut varier en fonction de la version du navigateur) :<br \/>\nAller sur Outils, Options Internet<br \/>\nCliquez sur Confidentialit\u00e9.<br \/>\nD\u00e9placez le curseur pour r\u00e9gler le niveau de confidentialit\u00e9 souhait\u00e9.<\/p>\n<p>Pour acc\u00e9der aux param\u00e8tres de cookies du navigateur Firefox, proc\u00e9dez comme suit (il peut varier en fonction de la version du navigateur) :<br \/>\nAcc\u00e9dez \u00e0 Options ou Pr\u00e9f\u00e9rences en fonction de votre syst\u00e8me d&#8217;exploitation.<br \/>\nCliquez sur Confidentialit\u00e9.<br \/>\nDans Historique, choisissez Utiliser les param\u00e8tres personnalis\u00e9s pour l&#8217;historique.<br \/>\nVous verrez l&#8217;option Accepter les cookies, vous pouvez l&#8217;activer ou le d\u00e9sactiver selon vos pr\u00e9f\u00e9rences.<br \/>\nPour acc\u00e9der aux param\u00e8tres de cookies du navigateur Safari pour OSX, proc\u00e9dez comme suit (il peut varier en fonction de la version du navigateur) :<br \/>\nAllez dans Pr\u00e9f\u00e9rences, puis Confidentialit\u00e9.<br \/>\nVous verrez l&#8217;option Bloquer les cookies pour ajuster le type de blocage que vous souhaitez effectuer.<\/p>\n<p>Pour acc\u00e9der aux param\u00e8tres de cookies du navigateur Safari pour iOS, proc\u00e9dez comme suit (il peut varier en fonction de la version du navigateur) :<br \/>\nAllez dans Param\u00e8tres, puis Safari.<br \/>\nAllez dans Confidentialit\u00e9 et s\u00e9curit\u00e9, vous verrez l&#8217;option Bloquer les cookies pour ajuster le type de blocage que vous souhaitez cr\u00e9er.<\/p>\n<p>Pour acc\u00e9der aux param\u00e8tres de cookies du navigateur pour les appareils Android, proc\u00e9dez comme suit (il peut varier en fonction de la version du navigateur) :<br \/>\nEx\u00e9cutez le navigateur et appuyez sur la touche Menu, puis sur Param\u00e8tres.<br \/>\nAllez dans S\u00e9curit\u00e9 et confidentialit\u00e9, vous verrez l\u2019option Accepter les cookies pour activer ou d\u00e9sactiver la case.<\/p>\n<p>Pour acc\u00e9der aux param\u00e8tres de cookies du navigateur pour les appareils Windows Phone, proc\u00e9dez comme suit (il peut varier en fonction de la version du navigateur) :<br \/>\nOuvrez Internet Explorer, puis Plus, puis Param\u00e8tres.<br \/>\nVous pouvez maintenant activer ou d\u00e9sactiver la case Autoriser les cookies.<\/p>\n<p><strong>Plus d&#8217;informations sur les cookies<\/strong><\/p>\n<p>Vous pouvez consulter le r\u00e8glement concernant les cookies publi\u00e9 par l&#8217;Agence Espagnole de Protection des Donn\u00e9es (AEPD) dans son &#8220;Guide d&#8217;utilisation des cookies&#8221; et obtenir plus d&#8217;informations sur les cookies sur Internet : http:\/\/www.aboutcookies.org\/<\/p>\n<p>Si vous souhaitez mieux contr\u00f4ler l\u2019installation des cookies, vous pouvez installer des programmes ou des modules compl\u00e9mentaires dans votre navigateur, connus sous le nom d\u2019outils \u00ab Do Not Track \u00bb, qui vous permettront de choisir les cookies que vous souhaitez autoriser.<\/p>\n<p>Selena Iberia a adapt\u00e9 le site Web \u00e0 la norme Do Not Track afin de garantir une plus grande confidentialit\u00e9 aux utilisateurs ayant activ\u00e9 cette option sur leur navigateur. Ce site exclut automatiquement du suivi les utilisateurs qui envoient l&#8217;en-t\u00eate Do Not Track de Google Analytics et est compatible avec leur acceptation expresse.<\/p>\n<p>Si vous le souhaitez, vous pouvez d\u00e9sactiver le suivi Google Analytics \u00e0 l&#8217;aide de cet add-on de navigateur propos\u00e9 par Google.<\/p>\n<p><strong>Remarques additionnelles <\/strong><\/p>\n<p>Ni ce site Web ni ses repr\u00e9sentants l\u00e9gaux ne sauraient \u00eatre tenus responsables ni du contenu ni de la v\u00e9racit\u00e9 des politiques de confidentialit\u00e9 des tiers mentionn\u00e9s dans cette politique de cookies.<\/p>\n<p>Les navigateurs Web sont les outils charg\u00e9s de stocker les cookies et c\u2019est depuis ces m\u00eames navigateurs que vous devez exercer votre droit de suppression ou de d\u00e9sactivation des cookies. Ni ce site Web ni ses repr\u00e9sentants l\u00e9gaux ne peuvent garantir le traitement correct ou incorrect des cookies par lesdits navigateurs.<\/p>\n<p>Dans certains cas, il est n\u00e9cessaire d\u2019installer des cookies pour que le navigateur n\u2019oublie pas votre d\u00e9cision de refus de ces derniers.<br \/>\nDans le cas des cookies de Google Analytics, Google stocke les cookies sur des serveurs situ\u00e9s aux \u00c9tats-Unis et s&#8217;engage \u00e0 ne pas les partager avec des tiers, sauf, le cas \u00e9ch\u00e9ant, pour le bon fonctionnement du syst\u00e8me ou lorsque la loi l&#8217;exigerait. Google affirme ne conserver pas votre adresse IP. Google Inc. est une entreprise signataire de l\u2019Accord sur la Sph\u00e8re de S\u00e9curit\u00e9 qui garantit que toutes les donn\u00e9es transf\u00e9r\u00e9es seront trait\u00e9es avec un niveau de protection conforme \u00e0 la r\u00e9glementation europ\u00e9enne.<\/p>\n<p>Pour toute question ou demande concernant cette politique de cookies, n&#8217;h\u00e9sitez pas \u00e0 nous contacter \u00e0 travers la section Contact.<\/p>\n<p><strong>Cette politique de cookies a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois le 25\/05\/2019.<\/strong>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1568387281259{margin-bottom: 50px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text el_class=&#8221;text_style&#8221;] POLITIQUE DE COOKIES Nous recueillons et utilisons les informations sur ce site web comme indiqu\u00e9 dans notre politique de confidentialit\u00e9. L&#8217;un des moyens par lesquels nous collectons des informations est via l\u2019utilisation d\u2019une technologie appel\u00e9e &#8220;cookies&#8221;. Dans Selena Iberia, nous utilisons des cookies pour plusieurs objectifs. Qu&#8217;est-ce qu&#8217;un &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"views\/template-blank.blade.php","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"h5ap_radio_sources":[],"footnotes":""},"class_list":["post-31013","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de cookies - Quilosa<\/title>\n<meta name=\"description\" content=\"V\u00e9rifiez le type de cookies utilis\u00e9s sur ce site Web pour collecter des informations comme indiqu\u00e9 dans notre politique de confidentialit\u00e9.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de cookies - Quilosa\" \/>\n<meta property=\"og:description\" content=\"V\u00e9rifiez le type de cookies utilis\u00e9s sur ce site Web pour collecter des informations comme indiqu\u00e9 dans notre politique de confidentialit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quilosa.com\/fr\/uso-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Quilosa\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-17T10:30:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/uso-de-cookies\\\/\",\"url\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/uso-de-cookies\\\/\",\"name\":\"Politique de cookies - Quilosa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/#website\"},\"datePublished\":\"2019-08-16T08:29:25+00:00\",\"dateModified\":\"2019-12-17T10:30:50+00:00\",\"description\":\"V\u00e9rifiez le type de cookies utilis\u00e9s sur ce site Web pour collecter des informations comme indiqu\u00e9 dans notre politique de confidentialit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/uso-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quilosa.com\\\/fr\\\/uso-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/uso-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/\",\"name\":\"Quilosa\",\"description\":\"L\u00edder en Productos Qu\u00edmicos para la Construcci\u00f3n, Industria y Bricolaje\",\"publisher\":{\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/#organization\",\"name\":\"Quilosa\",\"url\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quilosa.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo-quilosa-redondo-.png\",\"contentUrl\":\"https:\\\/\\\/quilosa.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo-quilosa-redondo-.png\",\"width\":591,\"height\":432,\"caption\":\"Quilosa\"},\"image\":{\"@id\":\"https:\\\/\\\/quilosa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de cookies - Quilosa","description":"V\u00e9rifiez le type de cookies utilis\u00e9s sur ce site Web pour collecter des informations comme indiqu\u00e9 dans notre politique de confidentialit\u00e9.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Politique de cookies - Quilosa","og_description":"V\u00e9rifiez le type de cookies utilis\u00e9s sur ce site Web pour collecter des informations comme indiqu\u00e9 dans notre politique de confidentialit\u00e9.","og_url":"https:\/\/quilosa.com\/fr\/uso-de-cookies\/","og_site_name":"Quilosa","article_modified_time":"2019-12-17T10:30:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/quilosa.com\/fr\/uso-de-cookies\/","url":"https:\/\/quilosa.com\/fr\/uso-de-cookies\/","name":"Politique de cookies - Quilosa","isPartOf":{"@id":"https:\/\/quilosa.com\/fr\/#website"},"datePublished":"2019-08-16T08:29:25+00:00","dateModified":"2019-12-17T10:30:50+00:00","description":"V\u00e9rifiez le type de cookies utilis\u00e9s sur ce site Web pour collecter des informations comme indiqu\u00e9 dans notre politique de confidentialit\u00e9.","breadcrumb":{"@id":"https:\/\/quilosa.com\/fr\/uso-de-cookies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quilosa.com\/fr\/uso-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/quilosa.com\/fr\/uso-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/quilosa.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de cookies"}]},{"@type":"WebSite","@id":"https:\/\/quilosa.com\/fr\/#website","url":"https:\/\/quilosa.com\/fr\/","name":"Quilosa","description":"L\u00edder en Productos Qu\u00edmicos para la Construcci\u00f3n, Industria y Bricolaje","publisher":{"@id":"https:\/\/quilosa.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quilosa.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/quilosa.com\/fr\/#organization","name":"Quilosa","url":"https:\/\/quilosa.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/quilosa.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/quilosa.com\/wp-content\/uploads\/2019\/12\/Logo-quilosa-redondo-.png","contentUrl":"https:\/\/quilosa.com\/wp-content\/uploads\/2019\/12\/Logo-quilosa-redondo-.png","width":591,"height":432,"caption":"Quilosa"},"image":{"@id":"https:\/\/quilosa.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/quilosa.com\/fr\/wp-json\/wp\/v2\/pages\/31013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quilosa.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/quilosa.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/quilosa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quilosa.com\/fr\/wp-json\/wp\/v2\/comments?post=31013"}],"version-history":[{"count":0,"href":"https:\/\/quilosa.com\/fr\/wp-json\/wp\/v2\/pages\/31013\/revisions"}],"wp:attachment":[{"href":"https:\/\/quilosa.com\/fr\/wp-json\/wp\/v2\/media?parent=31013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}